{"id":2599,"date":"2021-09-20T22:52:50","date_gmt":"2021-09-20T22:52:50","guid":{"rendered":"https:\/\/cotopaxi-travel.com\/blog\/?p=2599"},"modified":"2021-09-20T23:11:37","modified_gmt":"2021-09-20T23:11:37","slug":"la-mama-negra","status":"publish","type":"post","link":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/","title":{"rendered":"LA MAMA NEGRA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2599\" class=\"elementor elementor-2599\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b9a401 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b9a401\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e34427f\" data-id=\"e34427f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d5cfda elementor-widget elementor-widget-text-editor\" data-id=\"5d5cfda\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Mama Negra es una celebraci\u00f3n ecuatoriana, propia de la ciudad de Latacunga, \u00a0que se la conoce como la \u201cFiesta de la Capitan\u00eda\u201d o la \u201cSant\u00edsima Tragedia\u201d, la cual representa la uni\u00f3n de las culturas ind\u00edgenas espa\u00f1olas y africanas y su celebraci\u00f3n tiene lugar en los meses de septiembre donde se hace homenaje a la virgen de la Merced por haber calmado la furia del volc\u00e1n\u00a0<a href=\"https:\/\/cotopaxi-travel.com\/\" target=\"_blank\" rel=\"noopener\">Cotopaxi\u00a0<\/a>en el a\u00f1o 1742, y en noviembre por agasajar\u00a0 la independencia de esta colorida ciudad.<\/p><p>En esta celebraci\u00f3n las comparsas y las vestimentas hablan de personajes encantados que se esconden detr\u00e1s de un disfraz, para agradecer milagros y para atraer a la buena fortuna.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2576953 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2576953\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a8f282\" data-id=\"6a8f282\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6785ee5 elementor-widget elementor-widget-image\" data-id=\"6785ee5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"340\" src=\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-2.jpeg\" class=\"attachment-large size-large wp-image-2603\" alt=\"\" srcset=\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-2.jpeg 612w, https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-2-600x333.jpeg 600w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c82a7a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c82a7a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5393f65\" data-id=\"5393f65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-460eefb elementor-widget elementor-widget-text-editor\" data-id=\"460eefb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Personajes:<\/strong><\/p><p><strong>La Mama Negra:<\/strong> es el personaje principal de la fiesta, una esclava liberada matriarca de los esclavos africanos que fueron obligados a trabajar en las minas, cabalga en un hermosos caballo adornado, interpretada siempre por un hombre que viste de mujer que ti\u00f1e su rostro de color negro y sus labios de un intenso color rojo carmes\u00ed, vestido con prendas formales y coloridas, de su cabeza nace una larga y rizada cabellera adornada con cintas de colores y perlas artificiales, usa aretes de oro, sobre su cuello cuelgan hermosas y finas gargantillas y lleva en sus manos una mu\u00f1eca negra que representa a su hija menor a la que hace bailar al ritmo de la m\u00fasica interpretada por una banda de pueblo.<\/p><p><strong>El Capit\u00e1n:<\/strong> Es el prioste mayor de la comparsa un personaje que representa al alcalde espa\u00f1ol que fue asignado por el rey para gobernar este sector. Hace una marcha al ritmo de la banda popular y dirige a su delegaci\u00f3n con un sable. Al Capit\u00e1n le rinde homenaje todo el pueblo por ser la m\u00e1xima autoridad y su traje es de tipo militar.<\/p><p><strong>El \u00c1ngel de la Estrella:<\/strong> representa al arc\u00e1ngel Gabriel. Monta un caballo blanco, y viste de blanco como s\u00edmbolo de su pureza. Sobre su espalda van dos alas tambi\u00e9n blancas y un largo manto, sobre la cabeza porta una corona, en su mano diestra lleva un cetro con una estrella que gu\u00eda a todo el comit\u00e9 a un encuentro con la Virgen de la Merced.<\/p><p><strong>El Rey Moro:<\/strong> Simboliza la nobleza y solemnidad. Cabalga un caballo oscuro, lleva una capa ornamentada, sobre su cabeza luce un hermoso \u201ccapirote\u201d muy similar a los utilizados por los \u201cOrejones Precolombinos\u201d, en su pecho cubre con un hermoso tahal\u00ed y tambi\u00e9n usa un cetro para demostrar poder y autoridad.<\/p><p><strong>El Abanderado:<\/strong> Va a pie luciendo una bandera multicolor que contiene elementos andinos y espa\u00f1oles, representando la interculturalidad de los pueblos abor\u00edgenes. Su ropa es de corte militar y va acompa\u00f1ado por dos militares a su lado que visten con trajes similares al de aquel.<\/p><p><strong>Ashanguero:<\/strong> La creencias populares se\u00f1alan que era el esposo de la Mama Negra, denominado Taita Negro, encargado de llevar la comida a la Fiesta. Carga una ashanga (estructura de madera sobre la cual coloca una canasta) en su espalda, que contiene un chancho adobado con achiote, conejos, pollos y cuyes listos para ser cocinados. Adem\u00e1s lleva una canasta adornado con frutas, dulces, tabacos, licores y banderitas de los colores de Latacunga.<\/p><p><strong>Los Huacos:<\/strong> Llamados tambi\u00e9n brujos, son los que integran a las personas del p\u00fablico al desfile para hacer supuestas limpias, lo cual debe ser\u00a0 recompensado por un valor econ\u00f3mico.<\/p><p><strong>Las Camisonas:<\/strong> Son hombres vestidos de mujer que se encargan de despejar el camino llevando en la mano un l\u00e1tigo de cuero, adem\u00e1s visten con coloridos y raros trajes para llamar la atenci\u00f3n.<\/p><p><strong>El Champucero: <\/strong>Es un hombre pintado la cara de negro que abre paso para que la comparsa prosiga y lleva un balde con una colada de ma\u00edz que brinda a los espectadores en se\u00f1al de bienvenida.<\/p><p><strong>Los Loadores:<\/strong> Est\u00e1n pintados la cara de negro, llevan una botella de trago en sus manos que dan a la gente luego de una loa, son caracterizados como los poetas populares.<\/p><p>Estos, como otros personajes secundarios, dan vida a la comparsa y hacen que el p\u00fablico se sienta m\u00e1s integrado con estas fiestas tradicionales m\u00e1s emblem\u00e1ticas de la Provincia de <a href=\"https:\/\/cotopaxi-travel.com\/\">Cotopaxi.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-687390f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"687390f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47bc2ed\" data-id=\"47bc2ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b025ee elementor-widget elementor-widget-image\" data-id=\"5b025ee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"510\" src=\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-2.jpg\" class=\"attachment-large size-large wp-image-2602\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Mama Negra es una celebraci\u00f3n ecuatoriana, propia de la ciudad de Latacunga, &nbsp;que se la conoce como la \u201cFiesta de la Capitan\u00eda\u201d o la \u201cSant\u00edsima Tragedia\u201d, la cual representa la uni\u00f3n de las culturas ind\u00edgenas espa\u00f1olas y africanas y su celebraci\u00f3n tiene lugar en los meses de septiembre donde se hace homenaje a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2606,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3,65,2,67,7],"tags":[111,126,123,109,159,173],"class_list":["post-2599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adventure","category-climbing","category-culture","category-ecuador","category-travel","tag-cotopaxi","tag-cotopaxi-travel","tag-culture","tag-ecuador","tag-ecuador-tour","tag-explore-ecuador"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cotopaxi Travel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cotopaxi Travel\" \/>\n<meta property=\"og:description\" content=\"La Mama Negra es una celebraci\u00f3n ecuatoriana, propia de la ciudad de Latacunga, &nbsp;que se la conoce como la \u201cFiesta de la Capitan\u00eda\u201d o la \u201cSant\u00edsima Tragedia\u201d, la cual representa la uni\u00f3n de las culturas ind\u00edgenas espa\u00f1olas y africanas y su celebraci\u00f3n tiene lugar en los meses de septiembre donde se hace homenaje a la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\" \/>\n<meta property=\"og:site_name\" content=\"Cotopaxi Travel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cotopaxitraveltours\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cotopaxitraveltours\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-20T22:52:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-20T23:11:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CotopaxiTravel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/feriza81?lang=es\" \/>\n<meta name=\"twitter:site\" content=\"@es\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CotopaxiTravel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\"},\"author\":{\"name\":\"CotopaxiTravel\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5\"},\"headline\":\"LA MAMA NEGRA\",\"datePublished\":\"2021-09-20T22:52:50+00:00\",\"dateModified\":\"2021-09-20T23:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\"},\"wordCount\":736,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5\"},\"image\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg\",\"keywords\":[\"cotopaxi\",\"Cotopaxi-Travel\",\"Culture\",\"Ecuador\",\"ecuador tour\",\"explore ecuador\"],\"articleSection\":[\"Adventure\",\"Climbing\",\"Culture\",\"Ecuador\",\"Travel\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\",\"url\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\",\"name\":\"Cotopaxi Travel\",\"isPartOf\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg\",\"datePublished\":\"2021-09-20T22:52:50+00:00\",\"dateModified\":\"2021-09-20T23:11:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage\",\"url\":\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg\",\"contentUrl\":\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cotopaxi-travel.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA MAMA NEGRA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#website\",\"url\":\"https:\/\/cotopaxi-travel.com\/blog\/\",\"name\":\"Cotopaxi Travel\",\"description\":\"The Real Life Experiences\",\"publisher\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cotopaxi-travel.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5\",\"name\":\"CotopaxiTravel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo2-e1663084780999.png\",\"contentUrl\":\"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo2-e1663084780999.png\",\"width\":228,\"height\":226,\"caption\":\"CotopaxiTravel\"},\"logo\":{\"@id\":\"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/www.cotopaxi-travel.com\/\",\"https:\/\/www.facebook.com\/cotopaxitraveltours\",\"https:\/\/www.instagram.com\/cotopaxitravelec\/?hl=es\",\"https:\/\/www.pinterest.com\/cotopaxitravelec\/pins\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/feriza81?lang=es\",\"https:\/\/www.youtube.com\/channel\/UC_wpi32XPi0pKkwXM2xn8gg\",\"https:\/\/www.tumblr.com\/blog\/cotopaxitravelecu593\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cotopaxi Travel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/","og_locale":"es_ES","og_type":"article","og_title":"Cotopaxi Travel","og_description":"La Mama Negra es una celebraci\u00f3n ecuatoriana, propia de la ciudad de Latacunga, &nbsp;que se la conoce como la \u201cFiesta de la Capitan\u00eda\u201d o la \u201cSant\u00edsima Tragedia\u201d, la cual representa la uni\u00f3n de las culturas ind\u00edgenas espa\u00f1olas y africanas y su celebraci\u00f3n tiene lugar en los meses de septiembre donde se hace homenaje a la [&hellip;]","og_url":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/","og_site_name":"Cotopaxi Travel","article_publisher":"https:\/\/www.facebook.com\/cotopaxitraveltours","article_author":"https:\/\/www.facebook.com\/cotopaxitraveltours","article_published_time":"2021-09-20T22:52:50+00:00","article_modified_time":"2021-09-20T23:11:37+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg","type":"image\/jpeg"}],"author":"CotopaxiTravel","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/feriza81?lang=es","twitter_site":"@es","twitter_misc":{"Escrito por":"CotopaxiTravel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#article","isPartOf":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/"},"author":{"name":"CotopaxiTravel","@id":"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5"},"headline":"LA MAMA NEGRA","datePublished":"2021-09-20T22:52:50+00:00","dateModified":"2021-09-20T23:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/"},"wordCount":736,"commentCount":0,"publisher":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5"},"image":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage"},"thumbnailUrl":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg","keywords":["cotopaxi","Cotopaxi-Travel","Culture","Ecuador","ecuador tour","explore ecuador"],"articleSection":["Adventure","Climbing","Culture","Ecuador","Travel"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/","url":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/","name":"Cotopaxi Travel","isPartOf":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage"},"image":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage"},"thumbnailUrl":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg","datePublished":"2021-09-20T22:52:50+00:00","dateModified":"2021-09-20T23:11:37+00:00","breadcrumb":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#primaryimage","url":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg","contentUrl":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2021\/09\/mama-negra-1.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/cotopaxi-travel.com\/blog\/la-mama-negra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cotopaxi-travel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"LA MAMA NEGRA"}]},{"@type":"WebSite","@id":"https:\/\/cotopaxi-travel.com\/blog\/#website","url":"https:\/\/cotopaxi-travel.com\/blog\/","name":"Cotopaxi Travel","description":"The Real Life Experiences","publisher":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cotopaxi-travel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/2085677fd545aaca6274b07f4cc944d5","name":"CotopaxiTravel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo2-e1663084780999.png","contentUrl":"https:\/\/cotopaxi-travel.com\/blog\/wp-content\/uploads\/2022\/09\/cropped-cropped-logo2-e1663084780999.png","width":228,"height":226,"caption":"CotopaxiTravel"},"logo":{"@id":"https:\/\/cotopaxi-travel.com\/blog\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.cotopaxi-travel.com\/","https:\/\/www.facebook.com\/cotopaxitraveltours","https:\/\/www.instagram.com\/cotopaxitravelec\/?hl=es","https:\/\/www.pinterest.com\/cotopaxitravelec\/pins\/","https:\/\/x.com\/https:\/\/twitter.com\/feriza81?lang=es","https:\/\/www.youtube.com\/channel\/UC_wpi32XPi0pKkwXM2xn8gg","https:\/\/www.tumblr.com\/blog\/cotopaxitravelecu593"]}]}},"_links":{"self":[{"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/posts\/2599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/comments?post=2599"}],"version-history":[{"count":13,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/posts\/2599\/revisions"}],"predecessor-version":[{"id":2619,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/posts\/2599\/revisions\/2619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/media\/2606"}],"wp:attachment":[{"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/media?parent=2599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/categories?post=2599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cotopaxi-travel.com\/blog\/wp-json\/wp\/v2\/tags?post=2599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}